{"id":12,"count":6,"description":"","link":"https:\/\/malijai.fr\/index.php\/category\/mairie\/","name":"Mairie","slug":"mairie","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Mairie | Malijai.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/malijai.fr\/index.php\/category\/mairie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Mairie | Malijai.fr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/malijai.fr\/index.php\/category\/mairie\/\" \/>\n<meta property=\"og:site_name\" content=\"Malijai.fr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/malijai.fr\\\/index.php\\\/category\\\/mairie\\\/\",\"url\":\"https:\\\/\\\/malijai.fr\\\/index.php\\\/category\\\/mairie\\\/\",\"name\":\"Archives des Mairie | Malijai.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/malijai.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/malijai.fr\\\/index.php\\\/category\\\/mairie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/malijai.fr\\\/index.php\\\/category\\\/mairie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/malijai.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mairie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/malijai.fr\\\/#website\",\"url\":\"https:\\\/\\\/malijai.fr\\\/\",\"name\":\"Malijai.fr\",\"description\":\"Site internet de la commune de Malijai dans les Alpes de Haute-Provence\",\"publisher\":{\"@id\":\"https:\\\/\\\/malijai.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/malijai.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/malijai.fr\\\/#organization\",\"name\":\"Malijai\",\"url\":\"https:\\\/\\\/malijai.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/malijai.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.malijai.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/205467984_317221263388622_5064034598485676827_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.malijai.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/205467984_317221263388622_5064034598485676827_n.jpg\",\"width\":1697,\"height\":1080,\"caption\":\"Malijai\"},\"image\":{\"@id\":\"https:\\\/\\\/malijai.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MairieDeMalijai\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Mairie | Malijai.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/malijai.fr\/index.php\/category\/mairie\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Mairie | Malijai.fr","og_url":"https:\/\/malijai.fr\/index.php\/category\/mairie\/","og_site_name":"Malijai.fr","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/malijai.fr\/index.php\/category\/mairie\/","url":"https:\/\/malijai.fr\/index.php\/category\/mairie\/","name":"Archives des Mairie | Malijai.fr","isPartOf":{"@id":"https:\/\/malijai.fr\/#website"},"breadcrumb":{"@id":"https:\/\/malijai.fr\/index.php\/category\/mairie\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/malijai.fr\/index.php\/category\/mairie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/malijai.fr\/"},{"@type":"ListItem","position":2,"name":"Mairie"}]},{"@type":"WebSite","@id":"https:\/\/malijai.fr\/#website","url":"https:\/\/malijai.fr\/","name":"Malijai.fr","description":"Site internet de la commune de Malijai dans les Alpes de Haute-Provence","publisher":{"@id":"https:\/\/malijai.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/malijai.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/malijai.fr\/#organization","name":"Malijai","url":"https:\/\/malijai.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/malijai.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.malijai.fr\/wp-content\/uploads\/2021\/11\/205467984_317221263388622_5064034598485676827_n.jpg","contentUrl":"https:\/\/www.malijai.fr\/wp-content\/uploads\/2021\/11\/205467984_317221263388622_5064034598485676827_n.jpg","width":1697,"height":1080,"caption":"Malijai"},"image":{"@id":"https:\/\/malijai.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MairieDeMalijai"]}]}},"_links":{"self":[{"href":"https:\/\/malijai.fr\/index.php\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/malijai.fr\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/malijai.fr\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/malijai.fr\/index.php\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}